{"id":6992,"date":"2023-05-10T17:54:27","date_gmt":"2023-05-10T17:54:27","guid":{"rendered":"https:\/\/www.marmahats.com\/?post_type=product&#038;p=6992"},"modified":"2026-03-10T17:27:27","modified_gmt":"2026-03-10T16:27:27","slug":"sombrero-aimar","status":"publish","type":"product","link":"https:\/\/www.marmahats.com\/es\/producto\/sombrero-aimar\/","title":{"rendered":"Sombrero Aimar"},"content":{"rendered":"<p>Sombrero moderno en color tabaco, decorado con una cinta de fibra natural, cuarzo ahumado en la parte frontal y pirograbado pintado a mano.<\/p>\n<p>El cuarzo ahumado es conocido por sus propiedades de equilibrio y conexi\u00f3n con la tierra, lo que lo convierte en un gran accesorio para llevar durante las actividades cotidianas o en momentos en los que necesites un apoyo emocional extra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sombrero moderno en color tabaco, decorado con una cinta de fibra natural, cuarzo ahumado en la parte frontal y pirograbado pintado a mano.<\/p>\n<p>El cuarzo ahumado es conocido por sus propiedades de equilibrio y conexi\u00f3n con la tierra, lo que lo convierte en un gran accesorio para llevar durante las actividades cotidianas o en momentos en los que necesites un apoyo emocional extra.<\/p>\n","protected":false},"featured_media":6981,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[142,155],"product_tag":[],"class_list":{"0":"post-6992","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sombreros-gamuza","7":"product_cat-sombreros-pirograbados","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":true,"inbound_stock":0,"stock_on_hold":0,"sold_today":0,"sales_last_days":0,"reserved_stock":0,"customer_returns":0,"warehouse_damage":0,"lost_in_post":0,"other_logs":0,"out_stock_days":0,"lost_sales":0,"has_location":false,"update_date":"2026-05-13T00:39:47","atum_locations":[],"atum_stock_status":"outofstock","restock_status":false,"low_stock_amount":"","sales_update_date":"2026-05-13T00:39:47","calc_backorders":null,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product\/6992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/comments?post=6992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/media\/6981"}],"wp:attachment":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/media?parent=6992"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_brand?post=6992"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_cat?post=6992"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_tag?post=6992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}