{"id":6990,"date":"2023-05-10T17:52:39","date_gmt":"2023-05-10T17:52:39","guid":{"rendered":"https:\/\/www.marmahats.com\/?post_type=product&#038;p=6990"},"modified":"2026-04-21T17:15:48","modified_gmt":"2026-04-21T15:15:48","slug":"sombrero-luan","status":"publish","type":"product","link":"https:\/\/www.marmahats.com\/es\/producto\/sombrero-luan\/","title":{"rendered":"Sombrero Luan"},"content":{"rendered":"<p>Este sombrero de gamuza en color crudo est\u00e1 impregnado con la en\u00e9rgica piedra de cuarzo blanco y adornado con dise\u00f1os \u00e9tnicos de pirograbado.<\/p>\n<p>En la parte lateral del sombrero, una piedra de cuarzo est\u00e1 cuidadosamente incrustada en un engaste decorativo, creando un hermoso y \u00fanico punto focal. Esta gema es conocida por sus propiedades de equilibrio y conexi\u00f3n con la tierra, lo que la convierte en el complemento perfecto para tus accesorios diarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este sombrero de gamuza en color crudo est\u00e1 impregnado con la en\u00e9rgica piedra de cuarzo blanco y adornado con dise\u00f1os \u00e9tnicos de pirograbado.<\/p>\n<p>En la parte lateral del sombrero, una piedra de cuarzo est\u00e1 cuidadosamente incrustada en un engaste decorativo, creando un hermoso y \u00fanico punto focal. Esta gema es conocida por sus propiedades de equilibrio y conexi\u00f3n con la tierra, lo que la convierte en el complemento perfecto para tus accesorios diarios.<\/p>\n","protected":false},"featured_media":11767,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[142,155],"product_tag":[],"class_list":{"0":"post-6990","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sombreros-gamuza","7":"product_cat-sombreros-pirograbados","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"supplier_id":null,"supplier_sku":"","barcode":null,"atum_controlled":true,"out_stock_date":null,"out_stock_threshold":null,"inheritable":true,"inbound_stock":0,"stock_on_hold":0,"sold_today":0,"sales_last_days":0,"reserved_stock":0,"customer_returns":0,"warehouse_damage":0,"lost_in_post":0,"other_logs":0,"out_stock_days":0,"lost_sales":0,"has_location":false,"update_date":"2026-05-13T00:39:47","atum_locations":[],"atum_stock_status":"instock","restock_status":false,"low_stock_amount":"","sales_update_date":"2026-05-13T00:39:47","calc_backorders":null,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product\/6990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/comments?post=6990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/media\/11767"}],"wp:attachment":[{"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/media?parent=6990"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_brand?post=6990"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_cat?post=6990"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.marmahats.com\/es\/wp-json\/wp\/v2\/product_tag?post=6990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}